{"id":6934,"count":1,"description":"","link":"https:\/\/newsrajdhani.com\/index.php\/tag\/supreme-court-observation\/","name":"Supreme Court Observation","slug":"supreme-court-observation","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/newsrajdhani.com\/index.php\/wp-json\/wp\/v2\/tags\/6934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsrajdhani.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/newsrajdhani.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/newsrajdhani.com\/index.php\/wp-json\/wp\/v2\/posts?tags=6934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}